{"id":1253,"count":3,"description":"<p style=\"text-align: center\">Les fruits de citron \u00e9taient tenus en haute estime et largement utilis\u00e9s par les m\u00e9decins de l'Antiquit\u00e9 et du Moyen \u00c2ge. Les \u00c9gyptiens utilisaient les citrons pour combattre l'intoxication alimentaire et le typhus, reconnaissant leurs puissantes propri\u00e9t\u00e9s m\u00e9dicinales. Dans toute l'Europe, les citrons \u00e9taient salu\u00e9s comme un rem\u00e8de puissant contre la peste, le paludisme et la fi\u00e8vre, \u00e9galement v\u00e9n\u00e9r\u00e9s comme un antidote aux morsures de serpent. Les herboristes pr\u00f4naient l'utilisation de jus de citron pour r\u00e9guler la pression art\u00e9rielle, nettoyer le foie des toxines et soulager les douleurs articulaires.<\/p>\r\n<p style=\"text-align: center\">Avicenne, le c\u00e9l\u00e8bre polymathe perse, louait les fruits comme le rem\u00e8de principal contre les affections cardiaques et recommandait leur consommation pendant la grossesse et pour le traitement des troubles h\u00e9patiques. Les marins anglais portaient c\u00e9l\u00e8bres des citrons \u00e0 bord pour pr\u00e9venir le scorbut, une pratique qui soulignait le r\u00f4le vital du fruit dans le maintien de la sant\u00e9 lors de longs voyages en mer. Au milieu du XVIIe si\u00e8cle, les propri\u00e9t\u00e9s curatives des citrons ont \u00e9t\u00e9 officiellement reconnues, consolidant leur statut en tant qu'agent m\u00e9dicinal polyvalent.<\/p>\r\n<p style=\"text-align: center\">De plus, le parfum revigorant des citrons offre des avantages psychologiques, aidant \u00e0 l'adaptation \u00e0 de nouveaux environnements et favorisant la r\u00e9silience face aux d\u00e9fis. Il renforce la d\u00e9termination, stimule la cr\u00e9ativit\u00e9 tant dans le domaine professionnel que domestique, et sert de phare d'espoir en temps difficiles. Que ce soit consomm\u00e9 ou simplement appr\u00e9ci\u00e9 pour son essence aromatique, les citrons continuent d'\u00eatre v\u00e9n\u00e9r\u00e9s pour leurs contributions multiparit\u00e9s \u00e0 la sant\u00e9 et au bien-\u00eatre, tant physique qu'\u00e9motionnel.<\/p>","link":"https:\/\/smellslikespells.com\/fr\/head_notes\/citron\/","name":"Citron","slug":"citron","taxonomy":"head_notes","parent":0,"meta":[],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.0 (Yoast SEO v28.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Citron : R\u00e9v\u00e9lations sur les merveilles m\u00e9dicinales anciennes - smellslikespells.com<\/title>\n<meta name=\"description\" content=\"Les fruits de citron \u00e9taient tenus en haute estime et largement utilis\u00e9s par les m\u00e9decins de l&#039;Antiquit\u00e9 et du Moyen \u00c2ge.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/smellslikespells.com\/fr\/head_notes\/citron\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Citron\" \/>\n<meta property=\"og:description\" content=\"Les fruits de citron \u00e9taient tenus en haute estime et largement utilis\u00e9s par les m\u00e9decins de l&#039;Antiquit\u00e9 et du Moyen \u00c2ge.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/smellslikespells.com\/fr\/head_notes\/citron\/\" \/>\n<meta property=\"og:site_name\" content=\"smellslikespells.com\" \/>\n<meta property=\"og:image\" content=\"https:\/\/smellslikespells.com\/wp-content\/uploads\/2023\/09\/Smells-Like-Spells-INCANTATIONS-COLLECTION-2.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1240\" \/>\n\t<meta property=\"og:image:height\" content=\"650\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/smellslikespells.com\\\/fr\\\/head_notes\\\/citron\\\/\",\"url\":\"https:\\\/\\\/smellslikespells.com\\\/fr\\\/head_notes\\\/citron\\\/\",\"name\":\"Citron : R\u00e9v\u00e9lations sur les merveilles m\u00e9dicinales anciennes - smellslikespells.com\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/smellslikespells.com\\\/fr\\\/#website\"},\"description\":\"Les fruits de citron \u00e9taient tenus en haute estime et largement utilis\u00e9s par les m\u00e9decins de l'Antiquit\u00e9 et du Moyen \u00c2ge.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/smellslikespells.com\\\/fr\\\/head_notes\\\/citron\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/smellslikespells.com\\\/fr\\\/head_notes\\\/citron\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/smellslikespells.com\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Citron\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/smellslikespells.com\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/smellslikespells.com\\\/fr\\\/\",\"name\":\"Smells Like Spells\",\"description\":\"Boutique en ligne de bougies parfum\u00e9es artisanales, de parfums d&#039;int\u00e9rieur et d&#039;encens\",\"publisher\":{\"@id\":\"https:\\\/\\\/smellslikespells.com\\\/fr\\\/#organization\"},\"alternateName\":\"SmellsLikeSpells\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/smellslikespells.com\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/smellslikespells.com\\\/fr\\\/#organization\",\"name\":\"Smells Like Spells\",\"alternateName\":\"SmellsLikeSpells\",\"url\":\"https:\\\/\\\/smellslikespells.com\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/smellslikespells.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/smellslikespells.com\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/cropped-sls-logo.png\",\"contentUrl\":\"https:\\\/\\\/smellslikespells.com\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/cropped-sls-logo.png\",\"width\":512,\"height\":512,\"caption\":\"Smells Like Spells\"},\"image\":{\"@id\":\"https:\\\/\\\/smellslikespells.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/smellslikespells\\\/\",\"https:\\\/\\\/www.instagram.com\\\/smells_like_spells\\\/?hl=en\",\"https:\\\/\\\/www.pinterest.com\\\/smellsl\\\/\"],\"description\":\"Smells Like Spells is a Lithuanian home fragrance brand creating handcrafted scented candles, reed diffusers, home sprays, botanical incense and essential oil blends. Inspired by mythology, symbolism and nature, each collection is designed to create distinctive atmospheres through carefully crafted fragrances and premium natural ingredients.\",\"email\":\"hello@smellslikespells.com\",\"telephone\":\"+37060055718\",\"legalName\":\"UAB Magijos kvapas\",\"foundingDate\":\"2015-09-21\",\"vatID\":\"LT100004486212\",\"taxID\":\"300110300\",\"numberOfEmployees\":{\"@type\":\"QuantitativeValue\",\"minValue\":\"1\",\"maxValue\":\"10\"}}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Citron : R\u00e9v\u00e9lations sur les merveilles m\u00e9dicinales anciennes - smellslikespells.com","description":"Les fruits de citron \u00e9taient tenus en haute estime et largement utilis\u00e9s par les m\u00e9decins de l'Antiquit\u00e9 et du Moyen \u00c2ge.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/smellslikespells.com\/fr\/head_notes\/citron\/","og_locale":"fr_FR","og_type":"article","og_title":"Citron","og_description":"Les fruits de citron \u00e9taient tenus en haute estime et largement utilis\u00e9s par les m\u00e9decins de l'Antiquit\u00e9 et du Moyen \u00c2ge.","og_url":"https:\/\/smellslikespells.com\/fr\/head_notes\/citron\/","og_site_name":"smellslikespells.com","og_image":[{"width":1240,"height":650,"url":"https:\/\/smellslikespells.com\/wp-content\/uploads\/2023\/09\/Smells-Like-Spells-INCANTATIONS-COLLECTION-2.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/smellslikespells.com\/fr\/head_notes\/citron\/","url":"https:\/\/smellslikespells.com\/fr\/head_notes\/citron\/","name":"Citron : R\u00e9v\u00e9lations sur les merveilles m\u00e9dicinales anciennes - smellslikespells.com","isPartOf":{"@id":"https:\/\/smellslikespells.com\/fr\/#website"},"description":"Les fruits de citron \u00e9taient tenus en haute estime et largement utilis\u00e9s par les m\u00e9decins de l'Antiquit\u00e9 et du Moyen \u00c2ge.","breadcrumb":{"@id":"https:\/\/smellslikespells.com\/fr\/head_notes\/citron\/#breadcrumb"},"inLanguage":"fr-FR"},{"@type":"BreadcrumbList","@id":"https:\/\/smellslikespells.com\/fr\/head_notes\/citron\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/smellslikespells.com\/fr\/"},{"@type":"ListItem","position":2,"name":"Citron"}]},{"@type":"WebSite","@id":"https:\/\/smellslikespells.com\/fr\/#website","url":"https:\/\/smellslikespells.com\/fr\/","name":"Smells Like Spells","description":"Boutique en ligne de bougies parfum\u00e9es artisanales, de parfums d&#039;int\u00e9rieur et d&#039;encens","publisher":{"@id":"https:\/\/smellslikespells.com\/fr\/#organization"},"alternateName":"SmellsLikeSpells","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/smellslikespells.com\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/smellslikespells.com\/fr\/#organization","name":"Smells Like Spells","alternateName":"SmellsLikeSpells","url":"https:\/\/smellslikespells.com\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/smellslikespells.com\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/smellslikespells.com\/wp-content\/uploads\/2023\/05\/cropped-sls-logo.png","contentUrl":"https:\/\/smellslikespells.com\/wp-content\/uploads\/2023\/05\/cropped-sls-logo.png","width":512,"height":512,"caption":"Smells Like Spells"},"image":{"@id":"https:\/\/smellslikespells.com\/fr\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/smellslikespells\/","https:\/\/www.instagram.com\/smells_like_spells\/?hl=en","https:\/\/www.pinterest.com\/smellsl\/"],"description":"Smells Like Spells is a Lithuanian home fragrance brand creating handcrafted scented candles, reed diffusers, home sprays, botanical incense and essential oil blends. Inspired by mythology, symbolism and nature, each collection is designed to create distinctive atmospheres through carefully crafted fragrances and premium natural ingredients.","email":"hello@smellslikespells.com","telephone":"+37060055718","legalName":"UAB Magijos kvapas","foundingDate":"2015-09-21","vatID":"LT100004486212","taxID":"300110300","numberOfEmployees":{"@type":"QuantitativeValue","minValue":"1","maxValue":"10"}}]}},"_links":{"self":[{"href":"https:\/\/smellslikespells.com\/fr\/wp-json\/wp\/v2\/head_notes\/1253","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/smellslikespells.com\/fr\/wp-json\/wp\/v2\/head_notes"}],"about":[{"href":"https:\/\/smellslikespells.com\/fr\/wp-json\/wp\/v2\/taxonomies\/head_notes"}],"wp:post_type":[{"href":"https:\/\/smellslikespells.com\/fr\/wp-json\/wp\/v2\/product?head_notes=1253"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}