{"id":16223,"date":"2020-08-30T21:56:25","date_gmt":"2024-02-04T18:08:29","guid":{"rendered":"https:\/\/smellslikespells.com\/?post_type=product&#038;p=16223"},"modified":"2024-02-19T14:11:36","modified_gmt":"2024-02-19T12:11:36","slug":"melange-dhuiles-essentielles-idunn-2","status":"publish","type":"product","link":"https:\/\/smellslikespells.com\/fr\/produit\/melange-dhuiles-essentielles-idunn-2\/","title":{"rendered":"M\u00e9lange d\u2019huiles essentielles IDUNN"},"content":{"rendered":"<p>Le parfum magique de ce m\u00e9lange d\u2019huiles essentielles est compos\u00e9 selon des coutumes et des traditions anciennes, et se base sur la croyance que chaque plante et chaque ar\u00f4me a un pouvoir magique qui lui est propre. C\u2019est comme une recette de sorci\u00e8re dans laquelle chaque plante et ar\u00f4me a un r\u00f4le aromath\u00e9rapeutique et magique particulier. Les senteurs principales ont des propri\u00e9t\u00e9s aromath\u00e9rapeutiques compl\u00e9mentaires et cr\u00e9ent une riche pyramide olfactive dans laquelle chaque senteur est en harmonie avec les autres ar\u00f4mes.<\/p>\n<p>&nbsp;<\/p>\n<p><strong>N\u00e9roli\u00a0: <\/strong>le nom n\u00e9roli vient du nom d\u2019un prince italien du XVII\u00e8me si\u00e8cle qui habitait \u00e0 Nerola et adorait cette senteur, et qui la rendit populaire dans toute l\u2019Italie. On croit que l\u2019ar\u00f4me de fleur d\u2019oranger a des propri\u00e9t\u00e9s apaisantes et antiseptiques, aphrodisiaques, aide \u00e0 lutter contre la d\u00e9pression et l\u2019anxi\u00e9t\u00e9 et am\u00e9liore l\u2019humeur. Il peut \u00eatre utilis\u00e9 dans toute sorte de situation stressante\u00a0: entretien, examen, prise de parole en public, etc. en cas d\u2019insomnie, prenez un bain dans l\u2019eau duquel vous aurez ajout\u00e9 quelques gouttes de n\u00e9roli ou diffusez-en dans la soir\u00e9e. En Italie, les fleurs d\u2019oranger sont traditionnellement utilis\u00e9es pour la confection des couronnes de mari\u00e9es.<\/p>\n<p><strong>G\u00e9ranium\u00a0:<\/strong> on croit que l\u2019ar\u00f4me de g\u00e9ranium aide \u00e0 limiter le stress et \u00e0 faire venir des souvenirs plaisants, \u00e0 \u00e9quilibrer les \u00e9motions et en m\u00eame temps calme, apporte la tranquillit\u00e9 int\u00e9rieure et l\u2019espoir. Selon les anciennes recettes traditionnelles, l\u2019ar\u00f4me fait dispara\u00eetre la peur d\u2019aimer, de s\u2019engager et d\u2019\u00eatre abandonn\u00e9, aide \u00e0 donner plus d\u2019amour. L\u2019ar\u00f4me de g\u00e9ranium aide \u00e0 ouvrir son c\u0153ur et lib\u00e8re des souvenirs douloureux du pass\u00e9. Il diminue aussi les sautes d\u2019humeur.<\/p>\n<p><strong>Vanille\u00a0:<\/strong> la vanille vient de Mexico, du Panama et des Antilles. Les Azt\u00e8ques l\u2019appr\u00e9ciaient beaucoup la vanille comme \u00e9pice. Dans l\u2019Antiquit\u00e9, les gu\u00e9risseurs utilisaient le parfum de la vanille pour traiter les maladies mentales et les d\u00e9pressions nerveuses. On croit que l\u2019ar\u00f4me de vanille apporte un sentiment de s\u00e9curit\u00e9 dans l\u2019inconscient et soulage de l\u2019anxi\u00e9t\u00e9 et des peurs. Cette senteur calme, aide \u00e0 r\u00e9duire la col\u00e8re et les autres \u00e9motions n\u00e9gatives. Si vous voulez parler \u00e0 quelqu\u2019un de mani\u00e8re sinc\u00e8re, que quelqu\u2019un s\u2019ouvre \u00e0 vous et vous fasse confiance, parfumer la pi\u00e8ce avec de la vanille vous aidera.<\/p>\n<p><strong>C\u00e8dre de l\u2019Atlas\u00a0:<\/strong> on croit que le c\u00e8dre a un effet calmant, fortifiant, rajeunissant, qu\u2019il donne une impression de confort et est donc recommand\u00e9 en cas de peur, de danger, d\u2019hyst\u00e9rie, de col\u00e8re infond\u00e9s, ou d\u2019un autre comportement antipsychologique et contre l\u2019insomnie. Comme toutes les noix, la noix de c\u00e8dre symbolise l\u2019abondance et la richesse. Le c\u00e8dre renforce les qualit\u00e9s de leaders, la confiance en soi, la force et les qualit\u00e9s en g\u00e9n\u00e9ral.<\/p>\n<p>&nbsp;<\/p>\n<h5><strong>Avec ce m\u00e9lange d\u2019huiles essentielles vous trouverez :<\/strong><\/h5>\n<p>Une description d\u00e9taill\u00e9e des pouvoirs du m\u00e9lange d\u2019huiles essentielles\u00a0; une description de l\u2019effet aromath\u00e9rapeutique des diff\u00e9rentes senteurs\u00a0; un rituel simple de m\u00e9ditation\/affirmation qui vous aidera \u00e0 pr\u00e9server la beaut\u00e9 de votre jeunesse, revigorer votre corps et votre esprit, r\u00e9veiller votre sexualit\u00e9 et cr\u00e9er une atmosph\u00e8re sensuelle et romantique pour vous et celui ou celle que vous aimez.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Nous consacrons ce m\u00e9lange d\u2019huiles essentielles biologiques \u00e0 la d\u00e9esse scandinave Idunn. Nous croyons que le parfum magique de ce m\u00e9lange d\u2019huiles essentielles biologiques et le rituel simple de m\u00e9ditation\/affirmation (dont la description est fournie avec le m\u00e9lange d\u2019huiles essentielles) ainsi que l\u2019aide d\u2019Idunn vous aideront \u00e0 :<\/p>\n<ul>\n<li>Pr\u00e9server la beaut\u00e9 de votre jeunesse<\/li>\n<li>Revitaliser votre corps et votre \u00e2me<\/li>\n<li>\u00c9veiller votre sexualit\u00e9<\/li>\n<li>Cr\u00e9er une atmosph\u00e8re sensuelle et romantique pour vous et votre partenaire<\/li>\n<\/ul>\n<p>Dans la mythologie scandinave Idunn \u00e9tait la d\u00e9esse de la jeunesse et de l&#8217;immortalit\u00e9. Elle \u00e9tait la gardienne des pommes de la jeunesse \u00e9ternelle.<\/p>\n","protected":false},"featured_media":16217,"template":"","meta":[],"product_brand":[],"product_cat":[890,1466,1436],"product_tag":[1456],"head_notes":[1259,1223],"heart_notes":[1163],"base_notes":[1205,1258],"fragrance_family":[1649,1643,1585],"class_list":["post-16223","product","type-product","status-publish","has-post-thumbnail","product_cat-collection-norse-magic","product_cat-huiles-essentialles","product_cat-melange-dhuiles-essentielles","product_tag-beaute","head_notes-fleurs-doranger-neroli","head_notes-geranium-fr","heart_notes-1163","base_notes-cedre","base_notes-vanille","fragrance_family-boise-ambre","fragrance_family-boisee","fragrance_family-fleuri-boise","first","instock","taxable","shipping-taxable","purchasable","product-type-simple","thumb-has-effect","prod-rating-off"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.0 (Yoast SEO v28.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>M\u00e9lange d\u2019huiles essentielles IDUNN - smellslikespells.com<\/title>\n<meta name=\"description\" content=\"Nous consacrons ce m\u00e9lange d\u2019huiles essentielles biologiques \u00e0 la d\u00e9esse scandinave Idunn. Idunn \u00e9tait la d\u00e9esse de la jeunesse et de l&#039;immortalit\u00e9.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/smellslikespells.com\/fr\/produit\/melange-dhuiles-essentielles-idunn-2\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"M\u00e9lange d\u2019huiles essentielles IDUNN\" \/>\n<meta property=\"og:description\" content=\"Nous consacrons ce m\u00e9lange d\u2019huiles essentielles biologiques \u00e0 la d\u00e9esse scandinave Idunn. Idunn \u00e9tait la d\u00e9esse de la jeunesse et de l&#039;immortalit\u00e9.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/smellslikespells.com\/fr\/produit\/melange-dhuiles-essentielles-idunn-2\/\" \/>\n<meta property=\"og:site_name\" content=\"smellslikespells.com\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/smellslikespells\/\" \/>\n<meta property=\"article:modified_time\" content=\"2024-02-19T12:11:36+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/smellslikespells.com\/wp-content\/uploads\/2024\/02\/SMELLS-LIKE-SPELLS-organic-essential-oil-blend-IDUNN.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"1800\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data1\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/smellslikespells.com\\\/fr\\\/produit\\\/melange-dhuiles-essentielles-idunn-2\\\/\",\"url\":\"https:\\\/\\\/smellslikespells.com\\\/fr\\\/produit\\\/melange-dhuiles-essentielles-idunn-2\\\/\",\"name\":\"M\u00e9lange d\u2019huiles essentielles IDUNN - smellslikespells.com\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/smellslikespells.com\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/smellslikespells.com\\\/fr\\\/produit\\\/melange-dhuiles-essentielles-idunn-2\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/smellslikespells.com\\\/fr\\\/produit\\\/melange-dhuiles-essentielles-idunn-2\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/smellslikespells.com\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/SMELLS-LIKE-SPELLS-organic-essential-oil-blend-IDUNN.jpg\",\"datePublished\":\"2024-02-04T18:08:29+00:00\",\"dateModified\":\"2024-02-19T12:11:36+00:00\",\"description\":\"Nous consacrons ce m\u00e9lange d\u2019huiles essentielles biologiques \u00e0 la d\u00e9esse scandinave Idunn. Idunn \u00e9tait la d\u00e9esse de la jeunesse et de l'immortalit\u00e9.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/smellslikespells.com\\\/fr\\\/produit\\\/melange-dhuiles-essentielles-idunn-2\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/smellslikespells.com\\\/fr\\\/produit\\\/melange-dhuiles-essentielles-idunn-2\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/smellslikespells.com\\\/fr\\\/produit\\\/melange-dhuiles-essentielles-idunn-2\\\/#primaryimage\",\"url\":\"https:\\\/\\\/smellslikespells.com\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/SMELLS-LIKE-SPELLS-organic-essential-oil-blend-IDUNN.jpg\",\"contentUrl\":\"https:\\\/\\\/smellslikespells.com\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/SMELLS-LIKE-SPELLS-organic-essential-oil-blend-IDUNN.jpg\",\"width\":1200,\"height\":1800,\"caption\":\"M\u00e9lange d\u2019huiles essentielles IDUNN Smells Like Spells\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/smellslikespells.com\\\/fr\\\/produit\\\/melange-dhuiles-essentielles-idunn-2\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/smellslikespells.com\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Boutique\",\"item\":\"https:\\\/\\\/smellslikespells.com\\\/fr\\\/boutique\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"M\u00e9lange d\u2019huiles essentielles IDUNN\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/smellslikespells.com\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/smellslikespells.com\\\/fr\\\/\",\"name\":\"Smells Like Spells\",\"description\":\"Boutique en ligne de bougies parfum\u00e9es artisanales, de parfums d&#039;int\u00e9rieur et d&#039;encens\",\"publisher\":{\"@id\":\"https:\\\/\\\/smellslikespells.com\\\/fr\\\/#organization\"},\"alternateName\":\"SmellsLikeSpells\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/smellslikespells.com\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/smellslikespells.com\\\/fr\\\/#organization\",\"name\":\"Smells Like Spells\",\"alternateName\":\"SmellsLikeSpells\",\"url\":\"https:\\\/\\\/smellslikespells.com\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/smellslikespells.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/smellslikespells.com\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/cropped-sls-logo.png\",\"contentUrl\":\"https:\\\/\\\/smellslikespells.com\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/cropped-sls-logo.png\",\"width\":512,\"height\":512,\"caption\":\"Smells Like Spells\"},\"image\":{\"@id\":\"https:\\\/\\\/smellslikespells.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/smellslikespells\\\/\",\"https:\\\/\\\/www.instagram.com\\\/smells_like_spells\\\/?hl=en\",\"https:\\\/\\\/www.pinterest.com\\\/smellsl\\\/\"],\"description\":\"Smells Like Spells is a Lithuanian home fragrance brand creating handcrafted scented candles, reed diffusers, home sprays, botanical incense and essential oil blends. Inspired by mythology, symbolism and nature, each collection is designed to create distinctive atmospheres through carefully crafted fragrances and premium natural ingredients.\",\"email\":\"hello@smellslikespells.com\",\"telephone\":\"+37060055718\",\"legalName\":\"UAB Magijos kvapas\",\"foundingDate\":\"2015-09-21\",\"vatID\":\"LT100004486212\",\"taxID\":\"300110300\",\"numberOfEmployees\":{\"@type\":\"QuantitativeValue\",\"minValue\":\"1\",\"maxValue\":\"10\"}}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"M\u00e9lange d\u2019huiles essentielles IDUNN - smellslikespells.com","description":"Nous consacrons ce m\u00e9lange d\u2019huiles essentielles biologiques \u00e0 la d\u00e9esse scandinave Idunn. Idunn \u00e9tait la d\u00e9esse de la jeunesse et de l'immortalit\u00e9.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/smellslikespells.com\/fr\/produit\/melange-dhuiles-essentielles-idunn-2\/","og_locale":"fr_FR","og_type":"article","og_title":"M\u00e9lange d\u2019huiles essentielles IDUNN","og_description":"Nous consacrons ce m\u00e9lange d\u2019huiles essentielles biologiques \u00e0 la d\u00e9esse scandinave Idunn. Idunn \u00e9tait la d\u00e9esse de la jeunesse et de l'immortalit\u00e9.","og_url":"https:\/\/smellslikespells.com\/fr\/produit\/melange-dhuiles-essentielles-idunn-2\/","og_site_name":"smellslikespells.com","article_publisher":"https:\/\/www.facebook.com\/smellslikespells\/","article_modified_time":"2024-02-19T12:11:36+00:00","og_image":[{"width":1200,"height":1800,"url":"https:\/\/smellslikespells.com\/wp-content\/uploads\/2024\/02\/SMELLS-LIKE-SPELLS-organic-essential-oil-blend-IDUNN.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Dur\u00e9e de lecture estim\u00e9e":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/smellslikespells.com\/fr\/produit\/melange-dhuiles-essentielles-idunn-2\/","url":"https:\/\/smellslikespells.com\/fr\/produit\/melange-dhuiles-essentielles-idunn-2\/","name":"M\u00e9lange d\u2019huiles essentielles IDUNN - smellslikespells.com","isPartOf":{"@id":"https:\/\/smellslikespells.com\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/smellslikespells.com\/fr\/produit\/melange-dhuiles-essentielles-idunn-2\/#primaryimage"},"image":{"@id":"https:\/\/smellslikespells.com\/fr\/produit\/melange-dhuiles-essentielles-idunn-2\/#primaryimage"},"thumbnailUrl":"https:\/\/smellslikespells.com\/wp-content\/uploads\/2024\/02\/SMELLS-LIKE-SPELLS-organic-essential-oil-blend-IDUNN.jpg","datePublished":"2024-02-04T18:08:29+00:00","dateModified":"2024-02-19T12:11:36+00:00","description":"Nous consacrons ce m\u00e9lange d\u2019huiles essentielles biologiques \u00e0 la d\u00e9esse scandinave Idunn. Idunn \u00e9tait la d\u00e9esse de la jeunesse et de l'immortalit\u00e9.","breadcrumb":{"@id":"https:\/\/smellslikespells.com\/fr\/produit\/melange-dhuiles-essentielles-idunn-2\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/smellslikespells.com\/fr\/produit\/melange-dhuiles-essentielles-idunn-2\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/smellslikespells.com\/fr\/produit\/melange-dhuiles-essentielles-idunn-2\/#primaryimage","url":"https:\/\/smellslikespells.com\/wp-content\/uploads\/2024\/02\/SMELLS-LIKE-SPELLS-organic-essential-oil-blend-IDUNN.jpg","contentUrl":"https:\/\/smellslikespells.com\/wp-content\/uploads\/2024\/02\/SMELLS-LIKE-SPELLS-organic-essential-oil-blend-IDUNN.jpg","width":1200,"height":1800,"caption":"M\u00e9lange d\u2019huiles essentielles IDUNN Smells Like Spells"},{"@type":"BreadcrumbList","@id":"https:\/\/smellslikespells.com\/fr\/produit\/melange-dhuiles-essentielles-idunn-2\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/smellslikespells.com\/fr\/"},{"@type":"ListItem","position":2,"name":"Boutique","item":"https:\/\/smellslikespells.com\/fr\/boutique\/"},{"@type":"ListItem","position":3,"name":"M\u00e9lange d\u2019huiles essentielles IDUNN"}]},{"@type":"WebSite","@id":"https:\/\/smellslikespells.com\/fr\/#website","url":"https:\/\/smellslikespells.com\/fr\/","name":"Smells Like Spells","description":"Boutique en ligne de bougies parfum\u00e9es artisanales, de parfums d&#039;int\u00e9rieur et d&#039;encens","publisher":{"@id":"https:\/\/smellslikespells.com\/fr\/#organization"},"alternateName":"SmellsLikeSpells","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/smellslikespells.com\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/smellslikespells.com\/fr\/#organization","name":"Smells Like Spells","alternateName":"SmellsLikeSpells","url":"https:\/\/smellslikespells.com\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/smellslikespells.com\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/smellslikespells.com\/wp-content\/uploads\/2023\/05\/cropped-sls-logo.png","contentUrl":"https:\/\/smellslikespells.com\/wp-content\/uploads\/2023\/05\/cropped-sls-logo.png","width":512,"height":512,"caption":"Smells Like Spells"},"image":{"@id":"https:\/\/smellslikespells.com\/fr\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/smellslikespells\/","https:\/\/www.instagram.com\/smells_like_spells\/?hl=en","https:\/\/www.pinterest.com\/smellsl\/"],"description":"Smells Like Spells is a Lithuanian home fragrance brand creating handcrafted scented candles, reed diffusers, home sprays, botanical incense and essential oil blends. Inspired by mythology, symbolism and nature, each collection is designed to create distinctive atmospheres through carefully crafted fragrances and premium natural ingredients.","email":"hello@smellslikespells.com","telephone":"+37060055718","legalName":"UAB Magijos kvapas","foundingDate":"2015-09-21","vatID":"LT100004486212","taxID":"300110300","numberOfEmployees":{"@type":"QuantitativeValue","minValue":"1","maxValue":"10"}}]}},"_links":{"self":[{"href":"https:\/\/smellslikespells.com\/fr\/wp-json\/wp\/v2\/product\/16223","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/smellslikespells.com\/fr\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/smellslikespells.com\/fr\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/smellslikespells.com\/fr\/wp-json\/wp\/v2\/media\/16217"}],"wp:attachment":[{"href":"https:\/\/smellslikespells.com\/fr\/wp-json\/wp\/v2\/media?parent=16223"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/smellslikespells.com\/fr\/wp-json\/wp\/v2\/product_brand?post=16223"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/smellslikespells.com\/fr\/wp-json\/wp\/v2\/product_cat?post=16223"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/smellslikespells.com\/fr\/wp-json\/wp\/v2\/product_tag?post=16223"},{"taxonomy":"head_notes","embeddable":true,"href":"https:\/\/smellslikespells.com\/fr\/wp-json\/wp\/v2\/head_notes?post=16223"},{"taxonomy":"heart_notes","embeddable":true,"href":"https:\/\/smellslikespells.com\/fr\/wp-json\/wp\/v2\/heart_notes?post=16223"},{"taxonomy":"base_notes","embeddable":true,"href":"https:\/\/smellslikespells.com\/fr\/wp-json\/wp\/v2\/base_notes?post=16223"},{"taxonomy":"fragrance_family","embeddable":true,"href":"https:\/\/smellslikespells.com\/fr\/wp-json\/wp\/v2\/fragrance_family?post=16223"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}