{"id":7997,"date":"2020-04-15T12:11:20","date_gmt":"2020-04-15T09:11:20","guid":{"rendered":"https:\/\/smellslikespells.de\/?post_type=product&#038;p=7997"},"modified":"2025-11-06T12:01:24","modified_gmt":"2025-11-06T10:01:24","slug":"bougies-chauffe-plat-parfumees-frigga","status":"publish","type":"product","link":"https:\/\/smellslikespells.com\/fr\/produit\/bougies-chauffe-plat-parfumees-frigga\/","title":{"rendered":"Bougies chauffe-plat parfum\u00e9es FRIGGA"},"content":{"rendered":"<p>Le parfum magique de ces bougies chauffe &#8211; plat et sa recette pourront vous aider \u00e0 appr\u00e9cier les plaisirs de la vie et les d\u00e9sirs r\u00e9alis\u00e9s. Les notes principales se compl\u00e8tent les unes les autres avec des propri\u00e9t\u00e9s d&#8217;aromath\u00e9rapie et cr\u00e9ent une pyramide olfactive riche o\u00f9 chaque parfum a sa place en harmonie avec les autres ar\u00f4mes.<\/p>\n<p>&nbsp;<\/p>\n<p><strong>Grains de poivre noir<\/strong>\u00a0: leur ar\u00f4me aide \u00e0 r\u00e9duire la douleur, active la circulation sanguine, r\u00e9chauffe et a un effet positif sur les muscles et les articulations douloureuses, stimule et donne de l\u2019\u00e9nergie en cas de fatigue intense ou de froideur \u00e9motionnelle, ouvre l\u2019app\u00e9tit, d\u00e9tend, aide \u00e0 r\u00e9duire la fi\u00e8vre et est bon pour la digestion. Les ar\u00f4mes du poivre, comme ceux de toutes les \u00e9pices piquantes, nettoient le champ \u00e9nerg\u00e9tique, aident \u00e0 se d\u00e9barrasser des \u00e9nergies n\u00e9gatives et prot\u00e8gent contre les influences n\u00e9gatives de notre environnement.<\/p>\n<p><strong>Pamplemousse<\/strong>\u00a0: son parfum aide \u00e0 ouvrir son c\u0153ur, lib\u00e8re de la tristesse, de la nervosit\u00e9, de l\u2019anxi\u00e9t\u00e9. Il a un effet relaxant sur certaines personnes tandis que pour d\u2019autres il fonctionne comme un \u00e9nergisant et chasse la m\u00e9lancolie. Selon les anciennes recettes traditionnelles, l\u2019\u00e9nergie du parfum du pamplemousse rend optimiste, stimule le charme naturel et la confiance en soi, restaure le corps spirituel apr\u00e8s une maladie grave ou un choc \u00e9motionnel. L\u2019huile essentielle de pamplemousse est recommand\u00e9e en cas de besoin de chaleur spirituelle. En magie, le pamplemousse est en particulier associ\u00e9 \u00e0 la capacit\u00e9 \u00e0 attirer l\u2019amour.<\/p>\n<p><strong>Myrte<\/strong>\u00a0: a un effet positif sur les probl\u00e8mes neurologiques, aide \u00e0 respirer en cas d\u2019inflammation des voies respiratoires sup\u00e9rieures, calme et apaise. On croit que l\u2019odeur de myrte agit comme aphrodisiaque et stimule les fonctions reproductrices. Elle a un effet calmant et relaxant, peut aider en cas d\u2019impuissance, de frigidit\u00e9 ou de probl\u00e8mes d\u2019\u00e9rection. Le myrte est efficace pour aider \u00e0 perdre les mauvaises habitudes, et est donc un ingr\u00e9dient fr\u00e9quent des m\u00e9langes d\u00e9di\u00e9s aux personnes qui veulent arr\u00eater de fumer, ou se lib\u00e9rer d\u2019une addiction \u00e0 une drogue. En magie, le myrte est utilis\u00e9 pour les sortil\u00e8ges d\u2019amour et pour renforcer les liens dans un foyer et dans une famille.<\/p>\n<p><strong>Amande\u00a0<\/strong>: la noix et le bois de l\u2019amande sont utilis\u00e9s en magie depuis l\u2019Antiquit\u00e9. Le bois de l\u2019amandier fut m\u00eame utilis\u00e9 pour fabriquer les baguettes magiques. L\u2019amande est un symbole de richesse, de richesse mat\u00e9rielle et d\u2019abondance. Dans ce m\u00e9lange, l\u2019amande aide \u00e0 attirer la r\u00e9ussite financi\u00e8re, et la prosp\u00e9rit\u00e9. L\u2019odeur d\u2019amande apaise, cr\u00e9e une atmosph\u00e8re de s\u00e9curit\u00e9, de tranquillit\u00e9, de chaleur et d\u2019harmonie. L\u2019amande prot\u00e8ge aussi des influences \u00e9nerg\u00e9tiques n\u00e9gatives de l\u2019environnement, du mauvais \u0153il et des sortil\u00e8ges.<\/p>\n<p><strong>Laurier\u00a0<\/strong>: favorise la confiance en soi et le courage, aide \u00e0 \u00e9viter la peur, la tristesse et le stress. Selon les anciennes recettes traditionnelles, l\u2019huile essentielle de laurier est un excellent antiseptique, analg\u00e9sique, am\u00e9liore l\u2019app\u00e9tit. Les feuilles de laurier sont utilis\u00e9es en magie pour des rituels de d\u00e9sorcellement.<\/p>\n<p><strong>\u00c9pices orientales\u00a0:<\/strong>\u00a0l\u2019odeur des \u00e9pices orientales vous r\u00e9chauffera et vous donnera un sentiment d\u2019harmonie, de s\u00e9curit\u00e9 et de tranquillit\u00e9. Ce m\u00e9lange d\u2019herbes et d\u2019\u00e9pices diffuse les ar\u00f4mes de poivre, de coriandre, de fenouil, d\u2019anis et de safran. Comme les diff\u00e9rentes notes qui composent un accord, ces senteurs acqui\u00e8rent de nouvelles propri\u00e9t\u00e9s magiques et aromath\u00e9rapeutiques lorsqu\u2019elles sont associ\u00e9es, tout en conservant leur nature originelle. Le m\u00e9lange renforce les champs \u00e9nerg\u00e9tiques, \u00e9quilibre et calme.<\/p>\n<p><strong>Calambac<\/strong>\u00a0: utilis\u00e9 dans l\u2019encens et la parfumerie depuis l\u2019Antiquit\u00e9, mentionn\u00e9 dans de nombreuses sources \u00e9crites, comme les V\u00e9das, l\u2019ancien Testament, et les \u00e9critures religieuses de l\u2019Islam. Le calambac est consid\u00e9r\u00e9 comme une plante tellement puissante qu\u2019elle peut nettoyer l\u2019\u00e2me et en chasser les mauvais esprits. La m\u00e9decine chinoise traditionnelle consid\u00e8re le calambac comme une substance qui lib\u00e8re des spasmes et a des propri\u00e9t\u00e9s r\u00e9chauffantes, \u00e9quilibrantes, transformantes et qui aide \u00e0 \u00e9clairer l\u2019esprit et \u00e0 r\u00e9aliser ses objectifs.<\/p>\n<p><strong>Ambre gris\u00a0<\/strong>: c\u2019est une substance solide, inflammable et cireuse produite dans le syst\u00e8me digestif des cachalots et souvent appel\u00e9e \u00ab or flottant \u00bb. On la trouve en g\u00e9n\u00e9ral \u00e0 la surface de l\u2019eau ou d\u00e9pos\u00e9e sur les plages tropicales, elle est tr\u00e8s appr\u00e9ci\u00e9e par l\u2019industrie du parfum qui l\u2019utilise pour la fabrication de parfums luxueux. Cette substance cireuse et parfum\u00e9e est plus l\u00e9g\u00e8re que l\u2019eau et peut d\u00e9river sur les mers pendant des ann\u00e9es, o\u00f9 elle durcit sous l\u2019effet de l\u2019eau sal\u00e9e et du soleil. Lorsqu\u2019il est conserv\u00e9 dans un contenant herm\u00e9tique, l\u2019ambre gris diffuse une forte odeur musqu\u00e9e, tr\u00e8s appr\u00e9ci\u00e9e par les parfumeurs du monde entier, et qui a \u00e9t\u00e9 utilis\u00e9 comme un aphrodisiaque dans l\u2019Antiquit\u00e9. C\u2019est l\u2019un des ingr\u00e9dients le plus co\u00fbteux utilis\u00e9 dans les parfums. L\u2019odeur de l\u2019ambre gris est caract\u00e9ris\u00e9e par un ar\u00f4me musqu\u00e9 revigorant avec des touches orientales. L\u2019ambre gris fut longtemps consid\u00e9r\u00e9 comme un symbole du luxe.<\/p>\n<p><strong>C\u00e8dre\u00a0:<\/strong>\u00a0a un effet calmant, fortifiant, rajeunissant, qu\u2019il donne une impression de confort et est donc recommand\u00e9 en cas de peur, de danger, d\u2019hyst\u00e9rie, de col\u00e8re infond\u00e9s, ou d\u2019un autre comportement antipsychologique et contre l\u2019insomnie. Comme toutes les noix, la noix de c\u00e8dre symbolise l\u2019abondance et la richesse. Le c\u00e8dre renforce les qualit\u00e9s de leaders, la confiance en soi, la force et les qualit\u00e9s en g\u00e9n\u00e9ral.<\/p>\n<p><strong>Vanille\u00a0:<\/strong>\u00a0la vanille vient de Mexico, du Panama et des Antilles. Les Azt\u00e8ques l\u2019appr\u00e9ciaient beaucoup la vanille comme \u00e9pice. Dans l\u2019Antiquit\u00e9, les gu\u00e9risseurs utilisaient le parfum de la vanille pour traiter les maladies mentales et les d\u00e9pressions nerveuses. On croit que l\u2019ar\u00f4me de vanille apporte un sentiment de s\u00e9curit\u00e9 dans l\u2019inconscient et soulage de l\u2019anxi\u00e9t\u00e9 et des peurs. Cette senteur calme, aide \u00e0 r\u00e9duire la col\u00e8re et les autres \u00e9motions n\u00e9gatives. Si vous voulez parler \u00e0 quelqu\u2019un de mani\u00e8re sinc\u00e8re, que quelqu\u2019un s\u2019ouvre \u00e0 vous et vous fasse confiance, parfumer la pi\u00e8ce avec de la vanille vous aidera.<\/p>\n<p>&nbsp;<\/p>\n<h5>Avec ces bougies chauffe &#8211; plat fabriqu\u00e9es \u00e0 la main, vous recevrez :<\/h5>\n<p>Une description d\u00e9taill\u00e9e des objectifs de la\u00a0bougie chauffe &#8211; plat : une description des effets aromath\u00e9rapie des diff\u00e9rents parfums; un rituel simple de m\u00e9ditation \/ affirmation pour r\u00e9v\u00e9ler les pouvoirs de la bougie chauffe &#8211; plat aromatique. Le parfum magique de la bougie chauffe &#8211; plat pourra aider \u00e0 p<span lang=\"FR\">rot\u00e9ger votre maison et votre famille contre les invit\u00e9s ind\u00e9sirables et leurs mauvaises pens\u00e9es ; c<\/span><span lang=\"FR\">r\u00e9er de l&#8217;harmonie dans la maison ; a<\/span><span lang=\"FR\">pporter prosp\u00e9rit\u00e9 et richesse financi\u00e8re.<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p><span lang=\"FR\">Nous avons cr\u00e9\u00e9 <span lang=\"FR\">ces bougies chauffe &#8211; plat<\/span> pour ceux qui recherchent le confort et la chaleur du foyer familial, qui prot\u00e8gent leur maison et leur famille comme la prunelle de leurs yeux, dont la maison est leur forteresse.<\/span> <span lang=\"FR\">L\u2019ar\u00f4me magique des bougies chauffe-plats pourra aider \u00e0 :<\/span><\/p>\n<ul style=\"list-style-type: square;\">\n<li><span lang=\"FR\">Prot\u00e9ger votre maison et votre famille contre les invit\u00e9s ind\u00e9sirables et leurs mauvaises pens\u00e9es<\/span><\/li>\n<li><span lang=\"FR\">Cr\u00e9er de l&#8217;harmonie dans la maison<\/span><\/li>\n<li><span lang=\"FR\">Apporter prosp\u00e9rit\u00e9 et richesse financi\u00e8re<\/span><\/li>\n<\/ul>\n<p><span lang=\"FR\">Dans la mythologie nordique, Frigg, \u00e9pouse du dieu principal Odin, est la d\u00e9esse de la maison. Elle est la gardienne id\u00e9ale du foyer de la maison, la seule qui est autoris\u00e9e par son mari \u00e0 s&#8217;asseoir sur son tr\u00f4ne et \u00e0 regarder le monde entier.<\/span><\/p>\n","protected":false},"featured_media":17737,"template":"","meta":[],"product_brand":[],"product_cat":[883,880,890],"product_tag":[1829,1423,1851,1831],"head_notes":[1808,1232],"heart_notes":[1199,1202,1261,1475],"base_notes":[1286,1215,1205,1258],"fragrance_family":[1680,1668],"class_list":["post-7997","product","type-product","status-publish","has-post-thumbnail","product_cat-bougie-chauffe-plat-parfumee","product_cat-bougies","product_cat-collection-norse-magic","product_tag-famille","product_tag-foyer","product_tag-manoir-des-amandes","product_tag-partenariat","head_notes-citron-yuzu","head_notes-myrte","heart_notes-amande","heart_notes-epices-orientales","heart_notes-laurier","heart_notes-poivre-noir","base_notes-ambre-gris","base_notes-bois-dagar","base_notes-cedre","base_notes-vanille","fragrance_family-ambre-doux","fragrance_family-ambree-orientale","first","instock","taxable","shipping-taxable","purchasable","product-type-simple","thumb-has-effect","prod-rating-off"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.0 (Yoast SEO v28.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Bougies chauffe-plat parfum\u00e9es FRIGGA - smellslikespells.com<\/title>\n<meta name=\"description\" content=\"Ces bougies chauffe-plat ont \u00e9t\u00e9 confectionn\u00e9 \u00e0 Frigg, femme du chef des dieux et d\u00e9esse du foyer. Elles apportent une atmosph\u00e8re douillette et chaleureuse.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/smellslikespells.com\/fr\/produit\/bougies-chauffe-plat-parfumees-frigga\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Bougies chauffe-plat parfum\u00e9es FRIGGA\" \/>\n<meta property=\"og:description\" content=\"Ces bougies chauffe-plat ont \u00e9t\u00e9 confectionn\u00e9 \u00e0 Frigg, femme du chef des dieux et d\u00e9esse du foyer. Elles apportent une atmosph\u00e8re douillette et chaleureuse.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/smellslikespells.com\/fr\/produit\/bougies-chauffe-plat-parfumees-frigga\/\" \/>\n<meta property=\"og:site_name\" content=\"smellslikespells.com\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/smellslikespells\/\" \/>\n<meta property=\"article:modified_time\" content=\"2025-11-06T10:01:24+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/smellslikespells.com\/wp-content\/uploads\/2024\/02\/Scented-tealights-FRIGGA-3.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"1800\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data1\" content=\"5 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/smellslikespells.com\\\/fr\\\/produit\\\/bougies-chauffe-plat-parfumees-frigga\\\/\",\"url\":\"https:\\\/\\\/smellslikespells.com\\\/fr\\\/produit\\\/bougies-chauffe-plat-parfumees-frigga\\\/\",\"name\":\"Bougies chauffe-plat parfum\u00e9es FRIGGA - smellslikespells.com\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/smellslikespells.com\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/smellslikespells.com\\\/fr\\\/produit\\\/bougies-chauffe-plat-parfumees-frigga\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/smellslikespells.com\\\/fr\\\/produit\\\/bougies-chauffe-plat-parfumees-frigga\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/smellslikespells.com\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/Scented-tealights-FRIGGA-3.jpg\",\"datePublished\":\"2020-04-15T09:11:20+00:00\",\"dateModified\":\"2025-11-06T10:01:24+00:00\",\"description\":\"Ces bougies chauffe-plat ont \u00e9t\u00e9 confectionn\u00e9 \u00e0 Frigg, femme du chef des dieux et d\u00e9esse du foyer. Elles apportent une atmosph\u00e8re douillette et chaleureuse.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/smellslikespells.com\\\/fr\\\/produit\\\/bougies-chauffe-plat-parfumees-frigga\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/smellslikespells.com\\\/fr\\\/produit\\\/bougies-chauffe-plat-parfumees-frigga\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/smellslikespells.com\\\/fr\\\/produit\\\/bougies-chauffe-plat-parfumees-frigga\\\/#primaryimage\",\"url\":\"https:\\\/\\\/smellslikespells.com\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/Scented-tealights-FRIGGA-3.jpg\",\"contentUrl\":\"https:\\\/\\\/smellslikespells.com\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/Scented-tealights-FRIGGA-3.jpg\",\"width\":1200,\"height\":1800,\"caption\":\"Bougies chauffe-plat parfum\u00e9es FRIGGA Smells Like Spells\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/smellslikespells.com\\\/fr\\\/produit\\\/bougies-chauffe-plat-parfumees-frigga\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/smellslikespells.com\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Boutique\",\"item\":\"https:\\\/\\\/smellslikespells.com\\\/fr\\\/boutique\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Bougies chauffe-plat parfum\u00e9es FRIGGA\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/smellslikespells.com\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/smellslikespells.com\\\/fr\\\/\",\"name\":\"Smells Like Spells\",\"description\":\"Boutique en ligne de bougies parfum\u00e9es artisanales, de parfums d&#039;int\u00e9rieur et d&#039;encens\",\"publisher\":{\"@id\":\"https:\\\/\\\/smellslikespells.com\\\/fr\\\/#organization\"},\"alternateName\":\"SmellsLikeSpells\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/smellslikespells.com\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/smellslikespells.com\\\/fr\\\/#organization\",\"name\":\"Smells Like Spells\",\"alternateName\":\"SmellsLikeSpells\",\"url\":\"https:\\\/\\\/smellslikespells.com\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/smellslikespells.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/smellslikespells.com\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/cropped-sls-logo.png\",\"contentUrl\":\"https:\\\/\\\/smellslikespells.com\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/cropped-sls-logo.png\",\"width\":512,\"height\":512,\"caption\":\"Smells Like Spells\"},\"image\":{\"@id\":\"https:\\\/\\\/smellslikespells.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/smellslikespells\\\/\",\"https:\\\/\\\/www.instagram.com\\\/smells_like_spells\\\/?hl=en\",\"https:\\\/\\\/www.pinterest.com\\\/smellsl\\\/\"],\"description\":\"Smells Like Spells is a Lithuanian home fragrance brand creating handcrafted scented candles, reed diffusers, home sprays, botanical incense and essential oil blends. Inspired by mythology, symbolism and nature, each collection is designed to create distinctive atmospheres through carefully crafted fragrances and premium natural ingredients.\",\"email\":\"hello@smellslikespells.com\",\"telephone\":\"+37060055718\",\"legalName\":\"UAB Magijos kvapas\",\"foundingDate\":\"2015-09-21\",\"vatID\":\"LT100004486212\",\"taxID\":\"300110300\",\"numberOfEmployees\":{\"@type\":\"QuantitativeValue\",\"minValue\":\"1\",\"maxValue\":\"10\"}}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Bougies chauffe-plat parfum\u00e9es FRIGGA - smellslikespells.com","description":"Ces bougies chauffe-plat ont \u00e9t\u00e9 confectionn\u00e9 \u00e0 Frigg, femme du chef des dieux et d\u00e9esse du foyer. Elles apportent une atmosph\u00e8re douillette et chaleureuse.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/smellslikespells.com\/fr\/produit\/bougies-chauffe-plat-parfumees-frigga\/","og_locale":"fr_FR","og_type":"article","og_title":"Bougies chauffe-plat parfum\u00e9es FRIGGA","og_description":"Ces bougies chauffe-plat ont \u00e9t\u00e9 confectionn\u00e9 \u00e0 Frigg, femme du chef des dieux et d\u00e9esse du foyer. Elles apportent une atmosph\u00e8re douillette et chaleureuse.","og_url":"https:\/\/smellslikespells.com\/fr\/produit\/bougies-chauffe-plat-parfumees-frigga\/","og_site_name":"smellslikespells.com","article_publisher":"https:\/\/www.facebook.com\/smellslikespells\/","article_modified_time":"2025-11-06T10:01:24+00:00","og_image":[{"width":1200,"height":1800,"url":"https:\/\/smellslikespells.com\/wp-content\/uploads\/2024\/02\/Scented-tealights-FRIGGA-3.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Dur\u00e9e de lecture estim\u00e9e":"5 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/smellslikespells.com\/fr\/produit\/bougies-chauffe-plat-parfumees-frigga\/","url":"https:\/\/smellslikespells.com\/fr\/produit\/bougies-chauffe-plat-parfumees-frigga\/","name":"Bougies chauffe-plat parfum\u00e9es FRIGGA - smellslikespells.com","isPartOf":{"@id":"https:\/\/smellslikespells.com\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/smellslikespells.com\/fr\/produit\/bougies-chauffe-plat-parfumees-frigga\/#primaryimage"},"image":{"@id":"https:\/\/smellslikespells.com\/fr\/produit\/bougies-chauffe-plat-parfumees-frigga\/#primaryimage"},"thumbnailUrl":"https:\/\/smellslikespells.com\/wp-content\/uploads\/2024\/02\/Scented-tealights-FRIGGA-3.jpg","datePublished":"2020-04-15T09:11:20+00:00","dateModified":"2025-11-06T10:01:24+00:00","description":"Ces bougies chauffe-plat ont \u00e9t\u00e9 confectionn\u00e9 \u00e0 Frigg, femme du chef des dieux et d\u00e9esse du foyer. Elles apportent une atmosph\u00e8re douillette et chaleureuse.","breadcrumb":{"@id":"https:\/\/smellslikespells.com\/fr\/produit\/bougies-chauffe-plat-parfumees-frigga\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/smellslikespells.com\/fr\/produit\/bougies-chauffe-plat-parfumees-frigga\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/smellslikespells.com\/fr\/produit\/bougies-chauffe-plat-parfumees-frigga\/#primaryimage","url":"https:\/\/smellslikespells.com\/wp-content\/uploads\/2024\/02\/Scented-tealights-FRIGGA-3.jpg","contentUrl":"https:\/\/smellslikespells.com\/wp-content\/uploads\/2024\/02\/Scented-tealights-FRIGGA-3.jpg","width":1200,"height":1800,"caption":"Bougies chauffe-plat parfum\u00e9es FRIGGA Smells Like Spells"},{"@type":"BreadcrumbList","@id":"https:\/\/smellslikespells.com\/fr\/produit\/bougies-chauffe-plat-parfumees-frigga\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/smellslikespells.com\/fr\/"},{"@type":"ListItem","position":2,"name":"Boutique","item":"https:\/\/smellslikespells.com\/fr\/boutique\/"},{"@type":"ListItem","position":3,"name":"Bougies chauffe-plat parfum\u00e9es FRIGGA"}]},{"@type":"WebSite","@id":"https:\/\/smellslikespells.com\/fr\/#website","url":"https:\/\/smellslikespells.com\/fr\/","name":"Smells Like Spells","description":"Boutique en ligne de bougies parfum\u00e9es artisanales, de parfums d&#039;int\u00e9rieur et d&#039;encens","publisher":{"@id":"https:\/\/smellslikespells.com\/fr\/#organization"},"alternateName":"SmellsLikeSpells","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/smellslikespells.com\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/smellslikespells.com\/fr\/#organization","name":"Smells Like Spells","alternateName":"SmellsLikeSpells","url":"https:\/\/smellslikespells.com\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/smellslikespells.com\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/smellslikespells.com\/wp-content\/uploads\/2023\/05\/cropped-sls-logo.png","contentUrl":"https:\/\/smellslikespells.com\/wp-content\/uploads\/2023\/05\/cropped-sls-logo.png","width":512,"height":512,"caption":"Smells Like Spells"},"image":{"@id":"https:\/\/smellslikespells.com\/fr\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/smellslikespells\/","https:\/\/www.instagram.com\/smells_like_spells\/?hl=en","https:\/\/www.pinterest.com\/smellsl\/"],"description":"Smells Like Spells is a Lithuanian home fragrance brand creating handcrafted scented candles, reed diffusers, home sprays, botanical incense and essential oil blends. Inspired by mythology, symbolism and nature, each collection is designed to create distinctive atmospheres through carefully crafted fragrances and premium natural ingredients.","email":"hello@smellslikespells.com","telephone":"+37060055718","legalName":"UAB Magijos kvapas","foundingDate":"2015-09-21","vatID":"LT100004486212","taxID":"300110300","numberOfEmployees":{"@type":"QuantitativeValue","minValue":"1","maxValue":"10"}}]}},"_links":{"self":[{"href":"https:\/\/smellslikespells.com\/fr\/wp-json\/wp\/v2\/product\/7997","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/smellslikespells.com\/fr\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/smellslikespells.com\/fr\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/smellslikespells.com\/fr\/wp-json\/wp\/v2\/media\/17737"}],"wp:attachment":[{"href":"https:\/\/smellslikespells.com\/fr\/wp-json\/wp\/v2\/media?parent=7997"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/smellslikespells.com\/fr\/wp-json\/wp\/v2\/product_brand?post=7997"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/smellslikespells.com\/fr\/wp-json\/wp\/v2\/product_cat?post=7997"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/smellslikespells.com\/fr\/wp-json\/wp\/v2\/product_tag?post=7997"},{"taxonomy":"head_notes","embeddable":true,"href":"https:\/\/smellslikespells.com\/fr\/wp-json\/wp\/v2\/head_notes?post=7997"},{"taxonomy":"heart_notes","embeddable":true,"href":"https:\/\/smellslikespells.com\/fr\/wp-json\/wp\/v2\/heart_notes?post=7997"},{"taxonomy":"base_notes","embeddable":true,"href":"https:\/\/smellslikespells.com\/fr\/wp-json\/wp\/v2\/base_notes?post=7997"},{"taxonomy":"fragrance_family","embeddable":true,"href":"https:\/\/smellslikespells.com\/fr\/wp-json\/wp\/v2\/fragrance_family?post=7997"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}