{"id":8093,"date":"2020-04-15T12:15:46","date_gmt":"2020-04-15T09:15:46","guid":{"rendered":"https:\/\/smellslikespells.de\/?post_type=product&#038;p=8093"},"modified":"2025-08-11T15:35:45","modified_gmt":"2025-08-11T12:35:45","slug":"bougie-parfumee-bragi","status":"publish","type":"product","link":"https:\/\/smellslikespells.com\/fr\/produit\/bougie-parfumee-bragi\/","title":{"rendered":"Bougie parfum\u00e9e BRAGI"},"content":{"rendered":"<p>Le parfum magique de cette bougie parfum\u00e9e et sa recette pourront vous aider \u00e0 appr\u00e9cier les plaisirs de la vie et les d\u00e9sirs r\u00e9alis\u00e9s. Les notes principales se compl\u00e8tent les unes les autres avec des propri\u00e9t\u00e9s d&#8217;aromath\u00e9rapie et cr\u00e9ent une pyramide olfactive riche o\u00f9 chaque parfum a sa place en harmonie avec les autres ar\u00f4mes.<\/p>\n<p>&nbsp;<\/p>\n<p><strong>Encens indien :<\/strong>\u00a0cet encens authentique est produit \u00e0 partir des fleurs d\u2019un arbre sacr\u00e9. En Inde, il est appel\u00e9 \u201cnagakesara\u201d, \u201cnag champa\u201d ou l\u2019arbre du \u201csafran du cobra\u201d. En m\u00e9decine ayurv\u00e9dique, les extraits des fleurs, des graines, des feuilles et de l\u2019\u00e9corce de cette plante sont utilis\u00e9s depuis des temps imm\u00e9moriaux. Les arbres Nagakesara ou nag champa poussent dans de nombreux endroits, des pentes du sud de l\u2019Himalaya au Sri Lanka et aux \u00eeles Andaman. Le mesua ou bois de fer est un arbre de taille moyenne au bois exceptionnellement dur et aux fleurs parfum\u00e9es. L\u2019encens le plus subtil est fabriqu\u00e9 \u00e0 partir des fleurs de l\u2019arbre nag champa, qui symbolisent la sexualit\u00e9, la fertilit\u00e9, la passion et l\u2019amour.<\/p>\n<p><strong>Encens :<\/strong>\u00a0la plante a \u00e9t\u00e9 nomm\u00e9e d\u2019apr\u00e8s le mot fran\u00e7ais \u201cfranc\u201d, qui signifie \u201cluxueux\u201d. L\u2019encens est utilis\u00e9 depuis longtemps pour la production d\u2019encens. L\u2019encens (Boswellia) \u00e9tait l\u2019un des cadeaux des Rois mages \u00e0 l\u2019enfant J\u00e9sus. Dans la Gr\u00e8ce antique, la r\u00e9sine d\u2019encens \u00e9tait br\u00fbl\u00e9e sur les autels et dans les temples, car elle ralentit et approfondit la respiration, ce qui aide \u00e0 se calmer et \u00e0 s\u2019immerger dans la pri\u00e8re et la m\u00e9ditation. L\u2019odeur de l\u2019encens calme et apaise, et on l\u2019utilise encore aujourd\u2019hui pendant les m\u00e9ditations.<\/p>\n<p><strong>Bois de santal :<\/strong>\u00a0son ar\u00f4me harmonise et calme, aide \u00e0 r\u00e9duire le stress et l\u2019agitation. Il est un parfait stimulant de l\u2019humeur pour les personnes souffrant de d\u00e9pression, de peurs et de probl\u00e8mes quotidiens, aide en cas de d\u00e9pression nerveuse ou d\u2019anxi\u00e9t\u00e9. Les cultures orientales croient que cet ar\u00f4me attire particuli\u00e8rement les divinit\u00e9s, c\u2019est pourquoi l\u2019encens de bois de santal est souvent utilis\u00e9 pendant la m\u00e9ditation. Le bois de santal est aussi utilis\u00e9 pour construire des temples et des sculptures de dieux et de proph\u00e8tes.<\/p>\n<p><strong>Opium :<\/strong>\u00a0le parfum est froid, r\u00e9sineux, acide et amer, il donne de l\u2019\u00e9nergie et augmente la vigilance. Il \u00e9veille aussi la conscience, induit le r\u00eave conscient, cr\u00e9e un lien avec son propre subconscient, \u00e9voque et fait remonter les pens\u00e9es les plus secr\u00e8tes, aide \u00e0 comprendre les probl\u00e8mes profonds en les r\u00e9v\u00e9lant, aide \u00e0 analyser les causes et les effets de divers \u00e9v\u00e9nements et situations.<\/p>\n<p>&nbsp;<\/p>\n<h5><strong>Avec cette bougie parfum\u00e9e fabriqu\u00e9e \u00e0 la main, vous recevrez :\u00a0<\/strong><\/h5>\n<p>Une description d\u00e9taill\u00e9e des objectifs de la bougie parfum\u00e9e; une description des effets aromath\u00e9rapie des diff\u00e9rents parfums; un rituel simple de m\u00e9ditation\/affirmation pour r\u00e9v\u00e9ler les pouvoirs de la bougie parfum\u00e9e. Le parfum magique de la bougie parfum\u00e9e pourra aider \u00e0: garder propres vos pens\u00e9es et votre esprit ; trouver une solution dans des situations difficiles, \u00e9clairer l\u2019esprit ; d\u00e9velopper l\u2019intuition, \u00e9couter votre voix int\u00e9rieure ; atteindre l\u2019harmonie avec vous-m\u00eame et le monde.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Cette bougie parfum\u00e9e fabriqu\u00e9e \u00e0 la main est d\u00e9di\u00e9e \u00e0 Bragi \u2013 le dieu de l\u2019inspiration et de la cr\u00e9ativit\u00e9. Nous croyons qu\u2019un rituel simple de m\u00e9ditation \/ affirmation (dont la description est incluse) ainsi que l\u2019aide et l\u2019inspiration de Bragi pourront aider \u00e0 :<\/p>\n<ul style=\"list-style-type: square;\">\n<li>R\u00e9v\u00e9ler des pouvoirs cr\u00e9atifs<\/li>\n<li>D\u00e9velopper l\u2019intuition et entendre votre voix int\u00e9rieure<\/li>\n<li>\u00c9veiller les talents et comp\u00e9tences<\/li>\n<li>Inspirer artistes et cr\u00e9ateurs<\/li>\n<\/ul>\n<p>Dans la mythologie nordique, Bragi, le dieu de l\u2019\u00e9loquence et de la po\u00e9sie, a inspir\u00e9 les gens \u00e0 cr\u00e9er de la po\u00e9sie en leur donnant un verre d\u2019hydromel po\u00e9tique, fait avec le sang de Kvasir, le dieu de l\u2019inspiration.<\/p>\n","protected":false},"featured_media":17915,"template":"","meta":[],"product_brand":[],"product_cat":[882,880,890],"product_tag":[1463],"head_notes":[1473],"heart_notes":[1450],"base_notes":[1449,1251],"fragrance_family":[1680,1668],"class_list":["post-8093","product","type-product","status-publish","has-post-thumbnail","product_cat-bougies-parfumees","product_cat-bougies","product_cat-collection-norse-magic","product_tag-inspiration","head_notes-encens-indien","heart_notes-opium-fr","base_notes-bois-de-santal-fr","base_notes-encens-resine-oliban","fragrance_family-ambre-doux","fragrance_family-ambree-orientale","first","instock","taxable","shipping-taxable","purchasable","product-type-simple","thumb-has-effect","prod-rating-off"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.0 (Yoast SEO v28.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Bougie parfum\u00e9e BRAGI - smellslikespells.com<\/title>\n<meta name=\"description\" content=\"Cette bougie parfum\u00e9e fabriqu\u00e9es \u00e0 la main est d\u00e9di\u00e9 \u00e0 Bragi \u2013 le dieu de l\u2019inspiration. Cire de soja, m\u00e8che en bois, parfum magique et rituel magique.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/smellslikespells.com\/fr\/produit\/bougie-parfumee-bragi\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Bougie parfum\u00e9e BRAGI\" \/>\n<meta property=\"og:description\" content=\"Cette bougie parfum\u00e9e fabriqu\u00e9es \u00e0 la main est d\u00e9di\u00e9 \u00e0 Bragi \u2013 le dieu de l\u2019inspiration. Cire de soja, m\u00e8che en bois, parfum magique et rituel magique.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/smellslikespells.com\/fr\/produit\/bougie-parfumee-bragi\/\" \/>\n<meta property=\"og:site_name\" content=\"smellslikespells.com\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/smellslikespells\/\" \/>\n<meta property=\"article:modified_time\" content=\"2025-08-11T12:35:45+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/smellslikespells.com\/wp-content\/uploads\/2024\/03\/BRAGI_1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"1800\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data1\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/smellslikespells.com\\\/fr\\\/produit\\\/bougie-parfumee-bragi\\\/\",\"url\":\"https:\\\/\\\/smellslikespells.com\\\/fr\\\/produit\\\/bougie-parfumee-bragi\\\/\",\"name\":\"Bougie parfum\u00e9e BRAGI - smellslikespells.com\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/smellslikespells.com\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/smellslikespells.com\\\/fr\\\/produit\\\/bougie-parfumee-bragi\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/smellslikespells.com\\\/fr\\\/produit\\\/bougie-parfumee-bragi\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/smellslikespells.com\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/BRAGI_1.jpg\",\"datePublished\":\"2020-04-15T09:15:46+00:00\",\"dateModified\":\"2025-08-11T12:35:45+00:00\",\"description\":\"Cette bougie parfum\u00e9e fabriqu\u00e9es \u00e0 la main est d\u00e9di\u00e9 \u00e0 Bragi \u2013 le dieu de l\u2019inspiration. Cire de soja, m\u00e8che en bois, parfum magique et rituel magique.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/smellslikespells.com\\\/fr\\\/produit\\\/bougie-parfumee-bragi\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/smellslikespells.com\\\/fr\\\/produit\\\/bougie-parfumee-bragi\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/smellslikespells.com\\\/fr\\\/produit\\\/bougie-parfumee-bragi\\\/#primaryimage\",\"url\":\"https:\\\/\\\/smellslikespells.com\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/BRAGI_1.jpg\",\"contentUrl\":\"https:\\\/\\\/smellslikespells.com\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/BRAGI_1.jpg\",\"width\":1200,\"height\":1800,\"caption\":\"Bougie parfum\u00e9e en cire de soja avec m\u00e8che en bois BRAGI \u2013 Smells Like Spells\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/smellslikespells.com\\\/fr\\\/produit\\\/bougie-parfumee-bragi\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/smellslikespells.com\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Boutique\",\"item\":\"https:\\\/\\\/smellslikespells.com\\\/fr\\\/boutique\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Bougie parfum\u00e9e BRAGI\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/smellslikespells.com\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/smellslikespells.com\\\/fr\\\/\",\"name\":\"Smells Like Spells\",\"description\":\"Boutique en ligne de bougies parfum\u00e9es artisanales, de parfums d&#039;int\u00e9rieur et d&#039;encens\",\"publisher\":{\"@id\":\"https:\\\/\\\/smellslikespells.com\\\/fr\\\/#organization\"},\"alternateName\":\"SmellsLikeSpells\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/smellslikespells.com\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/smellslikespells.com\\\/fr\\\/#organization\",\"name\":\"Smells Like Spells\",\"alternateName\":\"SmellsLikeSpells\",\"url\":\"https:\\\/\\\/smellslikespells.com\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/smellslikespells.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/smellslikespells.com\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/cropped-sls-logo.png\",\"contentUrl\":\"https:\\\/\\\/smellslikespells.com\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/cropped-sls-logo.png\",\"width\":512,\"height\":512,\"caption\":\"Smells Like Spells\"},\"image\":{\"@id\":\"https:\\\/\\\/smellslikespells.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/smellslikespells\\\/\",\"https:\\\/\\\/www.instagram.com\\\/smells_like_spells\\\/?hl=en\",\"https:\\\/\\\/www.pinterest.com\\\/smellsl\\\/\"],\"description\":\"Smells Like Spells is a Lithuanian home fragrance brand creating handcrafted scented candles, reed diffusers, home sprays, botanical incense and essential oil blends. Inspired by mythology, symbolism and nature, each collection is designed to create distinctive atmospheres through carefully crafted fragrances and premium natural ingredients.\",\"email\":\"hello@smellslikespells.com\",\"telephone\":\"+37060055718\",\"legalName\":\"UAB Magijos kvapas\",\"foundingDate\":\"2015-09-21\",\"vatID\":\"LT100004486212\",\"taxID\":\"300110300\",\"numberOfEmployees\":{\"@type\":\"QuantitativeValue\",\"minValue\":\"1\",\"maxValue\":\"10\"}}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Bougie parfum\u00e9e BRAGI - smellslikespells.com","description":"Cette bougie parfum\u00e9e fabriqu\u00e9es \u00e0 la main est d\u00e9di\u00e9 \u00e0 Bragi \u2013 le dieu de l\u2019inspiration. Cire de soja, m\u00e8che en bois, parfum magique et rituel magique.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/smellslikespells.com\/fr\/produit\/bougie-parfumee-bragi\/","og_locale":"fr_FR","og_type":"article","og_title":"Bougie parfum\u00e9e BRAGI","og_description":"Cette bougie parfum\u00e9e fabriqu\u00e9es \u00e0 la main est d\u00e9di\u00e9 \u00e0 Bragi \u2013 le dieu de l\u2019inspiration. Cire de soja, m\u00e8che en bois, parfum magique et rituel magique.","og_url":"https:\/\/smellslikespells.com\/fr\/produit\/bougie-parfumee-bragi\/","og_site_name":"smellslikespells.com","article_publisher":"https:\/\/www.facebook.com\/smellslikespells\/","article_modified_time":"2025-08-11T12:35:45+00:00","og_image":[{"width":1200,"height":1800,"url":"https:\/\/smellslikespells.com\/wp-content\/uploads\/2024\/03\/BRAGI_1.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Dur\u00e9e de lecture estim\u00e9e":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/smellslikespells.com\/fr\/produit\/bougie-parfumee-bragi\/","url":"https:\/\/smellslikespells.com\/fr\/produit\/bougie-parfumee-bragi\/","name":"Bougie parfum\u00e9e BRAGI - smellslikespells.com","isPartOf":{"@id":"https:\/\/smellslikespells.com\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/smellslikespells.com\/fr\/produit\/bougie-parfumee-bragi\/#primaryimage"},"image":{"@id":"https:\/\/smellslikespells.com\/fr\/produit\/bougie-parfumee-bragi\/#primaryimage"},"thumbnailUrl":"https:\/\/smellslikespells.com\/wp-content\/uploads\/2024\/03\/BRAGI_1.jpg","datePublished":"2020-04-15T09:15:46+00:00","dateModified":"2025-08-11T12:35:45+00:00","description":"Cette bougie parfum\u00e9e fabriqu\u00e9es \u00e0 la main est d\u00e9di\u00e9 \u00e0 Bragi \u2013 le dieu de l\u2019inspiration. Cire de soja, m\u00e8che en bois, parfum magique et rituel magique.","breadcrumb":{"@id":"https:\/\/smellslikespells.com\/fr\/produit\/bougie-parfumee-bragi\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/smellslikespells.com\/fr\/produit\/bougie-parfumee-bragi\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/smellslikespells.com\/fr\/produit\/bougie-parfumee-bragi\/#primaryimage","url":"https:\/\/smellslikespells.com\/wp-content\/uploads\/2024\/03\/BRAGI_1.jpg","contentUrl":"https:\/\/smellslikespells.com\/wp-content\/uploads\/2024\/03\/BRAGI_1.jpg","width":1200,"height":1800,"caption":"Bougie parfum\u00e9e en cire de soja avec m\u00e8che en bois BRAGI \u2013 Smells Like Spells"},{"@type":"BreadcrumbList","@id":"https:\/\/smellslikespells.com\/fr\/produit\/bougie-parfumee-bragi\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/smellslikespells.com\/fr\/"},{"@type":"ListItem","position":2,"name":"Boutique","item":"https:\/\/smellslikespells.com\/fr\/boutique\/"},{"@type":"ListItem","position":3,"name":"Bougie parfum\u00e9e BRAGI"}]},{"@type":"WebSite","@id":"https:\/\/smellslikespells.com\/fr\/#website","url":"https:\/\/smellslikespells.com\/fr\/","name":"Smells Like Spells","description":"Boutique en ligne de bougies parfum\u00e9es artisanales, de parfums d&#039;int\u00e9rieur et d&#039;encens","publisher":{"@id":"https:\/\/smellslikespells.com\/fr\/#organization"},"alternateName":"SmellsLikeSpells","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/smellslikespells.com\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/smellslikespells.com\/fr\/#organization","name":"Smells Like Spells","alternateName":"SmellsLikeSpells","url":"https:\/\/smellslikespells.com\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/smellslikespells.com\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/smellslikespells.com\/wp-content\/uploads\/2023\/05\/cropped-sls-logo.png","contentUrl":"https:\/\/smellslikespells.com\/wp-content\/uploads\/2023\/05\/cropped-sls-logo.png","width":512,"height":512,"caption":"Smells Like Spells"},"image":{"@id":"https:\/\/smellslikespells.com\/fr\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/smellslikespells\/","https:\/\/www.instagram.com\/smells_like_spells\/?hl=en","https:\/\/www.pinterest.com\/smellsl\/"],"description":"Smells Like Spells is a Lithuanian home fragrance brand creating handcrafted scented candles, reed diffusers, home sprays, botanical incense and essential oil blends. Inspired by mythology, symbolism and nature, each collection is designed to create distinctive atmospheres through carefully crafted fragrances and premium natural ingredients.","email":"hello@smellslikespells.com","telephone":"+37060055718","legalName":"UAB Magijos kvapas","foundingDate":"2015-09-21","vatID":"LT100004486212","taxID":"300110300","numberOfEmployees":{"@type":"QuantitativeValue","minValue":"1","maxValue":"10"}}]}},"_links":{"self":[{"href":"https:\/\/smellslikespells.com\/fr\/wp-json\/wp\/v2\/product\/8093","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/smellslikespells.com\/fr\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/smellslikespells.com\/fr\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/smellslikespells.com\/fr\/wp-json\/wp\/v2\/media\/17915"}],"wp:attachment":[{"href":"https:\/\/smellslikespells.com\/fr\/wp-json\/wp\/v2\/media?parent=8093"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/smellslikespells.com\/fr\/wp-json\/wp\/v2\/product_brand?post=8093"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/smellslikespells.com\/fr\/wp-json\/wp\/v2\/product_cat?post=8093"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/smellslikespells.com\/fr\/wp-json\/wp\/v2\/product_tag?post=8093"},{"taxonomy":"head_notes","embeddable":true,"href":"https:\/\/smellslikespells.com\/fr\/wp-json\/wp\/v2\/head_notes?post=8093"},{"taxonomy":"heart_notes","embeddable":true,"href":"https:\/\/smellslikespells.com\/fr\/wp-json\/wp\/v2\/heart_notes?post=8093"},{"taxonomy":"base_notes","embeddable":true,"href":"https:\/\/smellslikespells.com\/fr\/wp-json\/wp\/v2\/base_notes?post=8093"},{"taxonomy":"fragrance_family","embeddable":true,"href":"https:\/\/smellslikespells.com\/fr\/wp-json\/wp\/v2\/fragrance_family?post=8093"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}