{"id":8152,"date":"2020-04-15T12:13:14","date_gmt":"2021-03-17T10:32:00","guid":{"rendered":"https:\/\/smellslikespells.de\/?post_type=product&#038;p=8152"},"modified":"2024-03-13T19:11:40","modified_gmt":"2024-03-13T17:11:40","slug":"bougie-parfumee-le-pape","status":"publish","type":"product","link":"https:\/\/smellslikespells.com\/fr\/produit\/bougie-parfumee-le-pape\/","title":{"rendered":"Bougie parfum\u00e9e HIGH PRIEST"},"content":{"rendered":"<p>Le parfum magique de cette bougie et sa recette\u00a0pourront vous aider \u00e0 appr\u00e9cier les plaisirs de la vie et les d\u00e9sirs r\u00e9alis\u00e9s. Les notes principales se compl\u00e8tent les unes les autres avec des propri\u00e9t\u00e9s d&#8217;aromath\u00e9rapie et cr\u00e9ent une pyramide olfactive riche o\u00f9 chaque parfum a sa place en harmonie avec les autres ar\u00f4mes.<\/p>\n<p>&nbsp;<\/p>\n<p><strong><span lang=\"FR\">Baies de geni\u00e8vre<\/span><\/strong><span lang=\"FR\">\u00a0: Depuis des temps anciens, le gen\u00e9vrier est utilis\u00e9 pour se prot\u00e9ger des mauvais esprits et les \u00e9loigner. Il prot\u00e8ge l\u2019aura des agressions, aide \u00e0 rapidement trouver une sortie de toute situation difficile. Il aide \u00e9galement \u00e0 \u00e9viter la col\u00e8re destructrice auto-cr\u00e9\u00e9e, \u00e0 obtenir l&#8217;autorit\u00e9 m\u00e9rit\u00e9e et \u00e0 d\u00e9velopper des qualit\u00e9s comme la noblesse, la gr\u00e2ce, etc.<\/span><\/p>\n<p><strong>R\u00e9glisse\u00a0<\/strong>: dans des tombes de pharaons, entre autres richesses, les scientifiques ont d\u00e9couvert des restes de racine de r\u00e9glisse. Cette plante \u00e9tait particuli\u00e8rement valoris\u00e9e et appr\u00e9ci\u00e9e. Depuis l&#8217;Antiquit\u00e9, la r\u00e9glisse a \u00e9galement \u00e9t\u00e9 utilis\u00e9e dans l&#8217;encens pour son ar\u00f4me qui influe positivement sur la jeunesse, la sexualit\u00e9, le charme et la sant\u00e9 physique.<\/p>\n<p><strong>Lilas<\/strong>\u00a0: l&#8217;ar\u00f4me purifiant du lilas a \u00e9t\u00e9 utilis\u00e9 dans des rituels magiques pour \u00e9liminer les sorts et les illusions, pour r\u00e9v\u00e9ler la v\u00e9rit\u00e9. Le parfum de lilas am\u00e9liore l&#8217;humeur, favorise les valeurs de bien commun et de partenariat, et \u00e9l\u00e8ve l&#8217;humeur et la personnalit\u00e9 \u00e0 un niveau spirituel sup\u00e9rieur.<\/p>\n<p><strong>Opium\u00a0<\/strong>: le parfum est froid, r\u00e9sineux, acide et amer, \u00e9nergise et augmente la vigilance. Il \u00e9veille la conscience, induit le r\u00eave conscient, cr\u00e9e un lien avec notre subconscient, \u00e9voque et \u00e9l\u00e8ve les pens\u00e9es les plus secr\u00e8tes, aide \u00e0 comprendre les probl\u00e8mes profonds en les r\u00e9v\u00e9lant, aide \u00e0 analyser les causes et effets de divers \u00e9v\u00e9nements et situations.<\/p>\n<p><strong><span lang=\"FR\">Myrrhe<\/span><\/strong><span lang=\"FR\">: les anciennes civilisations utilisaient la r\u00e9sine des arbres de myrrhe comme parfum et encens, ainsi qu&#8217;en m\u00e9decine. Le parfum de myrrhe aide \u00e0 trier les pens\u00e9es, emp\u00eache de c\u00e9der \u00e0 des d\u00e9tails non pertinents. Ce parfum convient particuli\u00e8rement \u00e0 la m\u00e9ditation, car il aide \u00e0 \u00e9loigner les pens\u00e9es \u00e9gocentriques, r\u00e9tablir l\u2019objectivit\u00e9 et l\u2019ad\u00e9quation de l\u2019\u00e9tat psychologique, calme l\u2019irritation et am\u00e9liore le sommeil. Il augmente \u00e9galement la sensibilit\u00e9 sexuelle.<\/span><\/p>\n<p>&nbsp;<\/p>\n<h5><span lang=\"FR-CA\">Avec cette luxueuse bougie, vous recevrez\u00a0:<\/span><\/h5>\n<p>Une description d\u00e9taill\u00e9e des objectifs de la bougie, une description des significations du parfum magique, une carte du jeu de Tarot que nous avons dessin\u00e9. Sa signification vous indiquera la qualit\u00e9 dominante actuelle de l\u2019arch\u00e9type <span lang=\"FR\">du Pape<\/span>.\u00a0Un rituel simple de m\u00e9ditation \/ affirmation pour r\u00e9v\u00e9ler les pouvoirs de la bougie aromatique qui pourront vous\u00a0<span lang=\"FR\">aider <\/span><span lang=\"FR\">\u00e0 renforcer le partenariat, harmoniser la famille et encourager le travail d&#8217;\u00e9quipe.\u00a0<\/span>Affirmations (du latin affirmatio &#8211; d\u00e9clarer, d\u00e9claration) \u2013 d\u00e9clarations positives que nous r\u00e9p\u00e9tons pour nous programmer, pour constamment nous changer nous-m\u00eames et notre pens\u00e9e, transformant ainsi \u00e9galement notre environnement proche. Notre subconscient est tr\u00e8s sensible aux phrases d\u00e9licates et figuratives souvent r\u00e9p\u00e9t\u00e9es, par cons\u00e9quent, les affirmations sont comme des programmes positifs que nous installons dans notre subconscient. Les affirmations r\u00e9p\u00e9t\u00e9es permettent de surmonter les obstacles et d&#8217;atteindre des objectifs qui semblaient impossibles.<\/p>\n","protected":false},"excerpt":{"rendered":"<p><span lang=\"FR\">Nous avons cr\u00e9\u00e9 cette collection de bougies faites \u00e0 la main \u00e0 partir des 22 cartes du jeu des Arcanes Majeurs du Tarot (arc\u0101nus en latin &#8211; myst\u00e8re). Ces 22 cartes peuvent \u00eatre interpr\u00e9t\u00e9es comme le chemin de d\u00e9veloppement spirituel de la naissance vers la perfection.<\/span><\/p>\n<p><span lang=\"FR\">La bougie portant le num\u00e9ro 5 des Arcanes Majeurs \u2013 Le Pape. Le Pape contr\u00f4le la tradition, les principes, le respect des valeurs universelles de l&#8217;humanit\u00e9. Cet arch\u00e9type des Arcanes Majeurs veille sur des groupes de personnes qui ont un objectif commun, qu&#8217;il s&#8217;agisse d&#8217;une famille, d&#8217;un groupe de coll\u00e8gues ou religieux. Le Pape transmet les r\u00e8gles du cosmos, la sagesse collective \u00e9crasante de l\u2019humanit\u00e9. <\/span><\/p>\n<p><span lang=\"FR\">Avec cette bougie, vous recevrez l\u2019une des 22 cartes des Arcanes Majeurs qui, en association avec Le Pape, pourra sugg\u00e9rer comment et \u00e0 quel niveau l\u2019arch\u00e9type du Pape se manifeste dans votre vie. Les affirmations sugg\u00e9r\u00e9es et le parfum magique de lilas, opium, r\u00e9glisse, baies de geni\u00e8vre et myrrhe pourront vous aider <\/span><span lang=\"FR\">\u00e0 renforcer le partenariat, harmoniser la famille et encourager le travail d&#8217;\u00e9quipe.<\/span><\/p>\n","protected":false},"featured_media":18001,"template":"","meta":[],"product_brand":[],"product_cat":[880,882,886],"product_tag":[1770,1447],"head_notes":[1225],"heart_notes":[1431,1450],"base_notes":[1209,1213],"fragrance_family":[1659,1643],"class_list":["post-8152","product","type-product","status-publish","has-post-thumbnail","product_cat-bougies","product_cat-bougies-parfumees","product_cat-major-arcana-collection","product_tag-intelligence","product_tag-relaxation","head_notes-lilas","heart_notes-baies-de-genievre-fr","heart_notes-opium-fr","base_notes-myrrhe","base_notes-reglisse","fragrance_family-boise-epice","fragrance_family-boisee","first","instock","taxable","shipping-taxable","purchasable","product-type-simple","thumb-has-effect","prod-rating-off"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.0 (Yoast SEO v28.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Bougie parfum\u00e9e HIGH PRIEST - smellslikespells.com<\/title>\n<meta name=\"description\" content=\"La bougie portant le num\u00e9ro 5 des Arcanes Majeurs \u2013 Le Pape. Cet arch\u00e9type veille sur des groupes de personnes qui ont un objectif commun.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/smellslikespells.com\/fr\/produit\/bougie-parfumee-le-pape\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Bougie parfum\u00e9e HIGH PRIEST\" \/>\n<meta property=\"og:description\" content=\"La bougie portant le num\u00e9ro 5 des Arcanes Majeurs \u2013 Le Pape. Cet arch\u00e9type veille sur des groupes de personnes qui ont un objectif commun.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/smellslikespells.com\/fr\/produit\/bougie-parfumee-le-pape\/\" \/>\n<meta property=\"og:site_name\" content=\"smellslikespells.com\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/smellslikespells\/\" \/>\n<meta property=\"article:modified_time\" content=\"2024-03-13T17:11:40+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/smellslikespells.com\/wp-content\/uploads\/2023\/09\/Smells-Like-Spells-INCANTATIONS-COLLECTION-2.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1240\" \/>\n\t<meta property=\"og:image:height\" content=\"650\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data1\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/smellslikespells.com\\\/fr\\\/produit\\\/bougie-parfumee-le-pape\\\/\",\"url\":\"https:\\\/\\\/smellslikespells.com\\\/fr\\\/produit\\\/bougie-parfumee-le-pape\\\/\",\"name\":\"Bougie parfum\u00e9e HIGH PRIEST - smellslikespells.com\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/smellslikespells.com\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/smellslikespells.com\\\/fr\\\/produit\\\/bougie-parfumee-le-pape\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/smellslikespells.com\\\/fr\\\/produit\\\/bougie-parfumee-le-pape\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/smellslikespells.com\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/THE-HIGH-PRIEST.jpg\",\"datePublished\":\"2021-03-17T10:32:00+00:00\",\"dateModified\":\"2024-03-13T17:11:40+00:00\",\"description\":\"La bougie portant le num\u00e9ro 5 des Arcanes Majeurs \u2013 Le Pape. Cet arch\u00e9type veille sur des groupes de personnes qui ont un objectif commun.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/smellslikespells.com\\\/fr\\\/produit\\\/bougie-parfumee-le-pape\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/smellslikespells.com\\\/fr\\\/produit\\\/bougie-parfumee-le-pape\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/smellslikespells.com\\\/fr\\\/produit\\\/bougie-parfumee-le-pape\\\/#primaryimage\",\"url\":\"https:\\\/\\\/smellslikespells.com\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/THE-HIGH-PRIEST.jpg\",\"contentUrl\":\"https:\\\/\\\/smellslikespells.com\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/THE-HIGH-PRIEST.jpg\",\"width\":1200,\"height\":1800,\"caption\":\"Bougie parfum\u00e9e THE HIGH PRIEST Smells Like Spells TAROT MAJOR ARCANA\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/smellslikespells.com\\\/fr\\\/produit\\\/bougie-parfumee-le-pape\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/smellslikespells.com\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Boutique\",\"item\":\"https:\\\/\\\/smellslikespells.com\\\/fr\\\/boutique\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Bougie parfum\u00e9e HIGH PRIEST\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/smellslikespells.com\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/smellslikespells.com\\\/fr\\\/\",\"name\":\"Smells Like Spells\",\"description\":\"Boutique en ligne de bougies parfum\u00e9es artisanales, de parfums d&#039;int\u00e9rieur et d&#039;encens\",\"publisher\":{\"@id\":\"https:\\\/\\\/smellslikespells.com\\\/fr\\\/#organization\"},\"alternateName\":\"SmellsLikeSpells\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/smellslikespells.com\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/smellslikespells.com\\\/fr\\\/#organization\",\"name\":\"Smells Like Spells\",\"alternateName\":\"SmellsLikeSpells\",\"url\":\"https:\\\/\\\/smellslikespells.com\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/smellslikespells.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/smellslikespells.com\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/cropped-sls-logo.png\",\"contentUrl\":\"https:\\\/\\\/smellslikespells.com\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/cropped-sls-logo.png\",\"width\":512,\"height\":512,\"caption\":\"Smells Like Spells\"},\"image\":{\"@id\":\"https:\\\/\\\/smellslikespells.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/smellslikespells\\\/\",\"https:\\\/\\\/www.instagram.com\\\/smells_like_spells\\\/?hl=en\",\"https:\\\/\\\/www.pinterest.com\\\/smellsl\\\/\"],\"description\":\"Smells Like Spells is a Lithuanian home fragrance brand creating handcrafted scented candles, reed diffusers, home sprays, botanical incense and essential oil blends. Inspired by mythology, symbolism and nature, each collection is designed to create distinctive atmospheres through carefully crafted fragrances and premium natural ingredients.\",\"email\":\"hello@smellslikespells.com\",\"telephone\":\"+37060055718\",\"legalName\":\"UAB Magijos kvapas\",\"foundingDate\":\"2015-09-21\",\"vatID\":\"LT100004486212\",\"taxID\":\"300110300\",\"numberOfEmployees\":{\"@type\":\"QuantitativeValue\",\"minValue\":\"1\",\"maxValue\":\"10\"}}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Bougie parfum\u00e9e HIGH PRIEST - smellslikespells.com","description":"La bougie portant le num\u00e9ro 5 des Arcanes Majeurs \u2013 Le Pape. Cet arch\u00e9type veille sur des groupes de personnes qui ont un objectif commun.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/smellslikespells.com\/fr\/produit\/bougie-parfumee-le-pape\/","og_locale":"fr_FR","og_type":"article","og_title":"Bougie parfum\u00e9e HIGH PRIEST","og_description":"La bougie portant le num\u00e9ro 5 des Arcanes Majeurs \u2013 Le Pape. Cet arch\u00e9type veille sur des groupes de personnes qui ont un objectif commun.","og_url":"https:\/\/smellslikespells.com\/fr\/produit\/bougie-parfumee-le-pape\/","og_site_name":"smellslikespells.com","article_publisher":"https:\/\/www.facebook.com\/smellslikespells\/","article_modified_time":"2024-03-13T17:11:40+00:00","og_image":[{"width":1240,"height":650,"url":"https:\/\/smellslikespells.com\/wp-content\/uploads\/2023\/09\/Smells-Like-Spells-INCANTATIONS-COLLECTION-2.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Dur\u00e9e de lecture estim\u00e9e":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/smellslikespells.com\/fr\/produit\/bougie-parfumee-le-pape\/","url":"https:\/\/smellslikespells.com\/fr\/produit\/bougie-parfumee-le-pape\/","name":"Bougie parfum\u00e9e HIGH PRIEST - smellslikespells.com","isPartOf":{"@id":"https:\/\/smellslikespells.com\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/smellslikespells.com\/fr\/produit\/bougie-parfumee-le-pape\/#primaryimage"},"image":{"@id":"https:\/\/smellslikespells.com\/fr\/produit\/bougie-parfumee-le-pape\/#primaryimage"},"thumbnailUrl":"https:\/\/smellslikespells.com\/wp-content\/uploads\/2024\/03\/THE-HIGH-PRIEST.jpg","datePublished":"2021-03-17T10:32:00+00:00","dateModified":"2024-03-13T17:11:40+00:00","description":"La bougie portant le num\u00e9ro 5 des Arcanes Majeurs \u2013 Le Pape. Cet arch\u00e9type veille sur des groupes de personnes qui ont un objectif commun.","breadcrumb":{"@id":"https:\/\/smellslikespells.com\/fr\/produit\/bougie-parfumee-le-pape\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/smellslikespells.com\/fr\/produit\/bougie-parfumee-le-pape\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/smellslikespells.com\/fr\/produit\/bougie-parfumee-le-pape\/#primaryimage","url":"https:\/\/smellslikespells.com\/wp-content\/uploads\/2024\/03\/THE-HIGH-PRIEST.jpg","contentUrl":"https:\/\/smellslikespells.com\/wp-content\/uploads\/2024\/03\/THE-HIGH-PRIEST.jpg","width":1200,"height":1800,"caption":"Bougie parfum\u00e9e THE HIGH PRIEST Smells Like Spells TAROT MAJOR ARCANA"},{"@type":"BreadcrumbList","@id":"https:\/\/smellslikespells.com\/fr\/produit\/bougie-parfumee-le-pape\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/smellslikespells.com\/fr\/"},{"@type":"ListItem","position":2,"name":"Boutique","item":"https:\/\/smellslikespells.com\/fr\/boutique\/"},{"@type":"ListItem","position":3,"name":"Bougie parfum\u00e9e HIGH PRIEST"}]},{"@type":"WebSite","@id":"https:\/\/smellslikespells.com\/fr\/#website","url":"https:\/\/smellslikespells.com\/fr\/","name":"Smells Like Spells","description":"Boutique en ligne de bougies parfum\u00e9es artisanales, de parfums d&#039;int\u00e9rieur et d&#039;encens","publisher":{"@id":"https:\/\/smellslikespells.com\/fr\/#organization"},"alternateName":"SmellsLikeSpells","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/smellslikespells.com\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/smellslikespells.com\/fr\/#organization","name":"Smells Like Spells","alternateName":"SmellsLikeSpells","url":"https:\/\/smellslikespells.com\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/smellslikespells.com\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/smellslikespells.com\/wp-content\/uploads\/2023\/05\/cropped-sls-logo.png","contentUrl":"https:\/\/smellslikespells.com\/wp-content\/uploads\/2023\/05\/cropped-sls-logo.png","width":512,"height":512,"caption":"Smells Like Spells"},"image":{"@id":"https:\/\/smellslikespells.com\/fr\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/smellslikespells\/","https:\/\/www.instagram.com\/smells_like_spells\/?hl=en","https:\/\/www.pinterest.com\/smellsl\/"],"description":"Smells Like Spells is a Lithuanian home fragrance brand creating handcrafted scented candles, reed diffusers, home sprays, botanical incense and essential oil blends. Inspired by mythology, symbolism and nature, each collection is designed to create distinctive atmospheres through carefully crafted fragrances and premium natural ingredients.","email":"hello@smellslikespells.com","telephone":"+37060055718","legalName":"UAB Magijos kvapas","foundingDate":"2015-09-21","vatID":"LT100004486212","taxID":"300110300","numberOfEmployees":{"@type":"QuantitativeValue","minValue":"1","maxValue":"10"}}]}},"_links":{"self":[{"href":"https:\/\/smellslikespells.com\/fr\/wp-json\/wp\/v2\/product\/8152","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/smellslikespells.com\/fr\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/smellslikespells.com\/fr\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/smellslikespells.com\/fr\/wp-json\/wp\/v2\/media\/18001"}],"wp:attachment":[{"href":"https:\/\/smellslikespells.com\/fr\/wp-json\/wp\/v2\/media?parent=8152"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/smellslikespells.com\/fr\/wp-json\/wp\/v2\/product_brand?post=8152"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/smellslikespells.com\/fr\/wp-json\/wp\/v2\/product_cat?post=8152"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/smellslikespells.com\/fr\/wp-json\/wp\/v2\/product_tag?post=8152"},{"taxonomy":"head_notes","embeddable":true,"href":"https:\/\/smellslikespells.com\/fr\/wp-json\/wp\/v2\/head_notes?post=8152"},{"taxonomy":"heart_notes","embeddable":true,"href":"https:\/\/smellslikespells.com\/fr\/wp-json\/wp\/v2\/heart_notes?post=8152"},{"taxonomy":"base_notes","embeddable":true,"href":"https:\/\/smellslikespells.com\/fr\/wp-json\/wp\/v2\/base_notes?post=8152"},{"taxonomy":"fragrance_family","embeddable":true,"href":"https:\/\/smellslikespells.com\/fr\/wp-json\/wp\/v2\/fragrance_family?post=8152"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}